{"id":1295,"date":"2012-04-10T03:42:16","date_gmt":"2012-04-10T03:42:16","guid":{"rendered":"http:\/\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg"},"modified":"2012-04-10T03:42:16","modified_gmt":"2012-04-10T03:42:16","slug":"100_0693","status":"inherit","type":"attachment","link":"http:\/\/www.acrossutah.com\/wordpress\/across-canyonlands\/100_0693\/","title":{"rendered":"Camp View at Millard Canyon"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-1295","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a3aFWl-kT","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"166\" src=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?fit=300%2C166\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?w=900 900w, https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?resize=300%2C166 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"1295\" data-permalink=\"http:\/\/www.acrossutah.com\/wordpress\/across-canyonlands\/100_0693\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?fit=900%2C500\" data-orig-size=\"900,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;KODAK P880 ZOOM DIGITAL CAMERA&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1178478207&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Camp View at Millard Canyon\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?fit=300%2C166\" data-large-file=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?fit=800%2C444\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"http:\/\/www.acrossutah.com\/wordpress\/across-canyonlands\/100_0693\/\">Continue reading<\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"900","height":"500","hwstring_small":"height='71' width='128'","file":"2007\/05\/100_0693.jpg","sizes":{"thumbnail":{"file":"100_0693-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?resize=150%2C150"},"medium":{"file":"100_0693-300x166.jpg","width":"300","height":"166","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?fit=300%2C166"},"post-thumbnail":{"file":"100_0693-900x198.jpg","width":"900","height":"198","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?fit=150%2C33"},"full":{"file":"100_0693.jpg?fit=900%2C500","width":900,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg?fit=900%2C500"}},"image_meta":{"aperture":"4.5","credit":"","camera":"KODAK P880 ZOOM DIGITAL CAMERA","caption":"","created_timestamp":"1178478207","copyright":"","focal_length":"5","iso":"200","shutter_speed":"0.016666666666667","title":""}},"post":558,"source_url":"http:\/\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2007\/05\/100_0693.jpg","_links":{"self":[{"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/media\/1295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/comments?post=1295"}]}}