{"id":10036,"date":"2019-12-31T22:25:33","date_gmt":"2019-12-31T22:25:33","guid":{"rendered":"http:\/\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg"},"modified":"2019-12-31T22:25:33","modified_gmt":"2019-12-31T22:25:33","slug":"hoodoos-2","status":"inherit","type":"attachment","link":"http:\/\/www.acrossutah.com\/wordpress\/best-of-the-decade\/hoodoos-2\/","title":{"rendered":"Hoodoos"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-10036","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a3aFWl-2BS","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" src=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=500%2C281\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?w=2000 2000w, https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=500%2C281 500w, https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=768%2C432 768w, https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=800%2C450 800w, https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=150%2C84 150w, https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?w=1600 1600w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" data-attachment-id=\"10036\" data-permalink=\"http:\/\/www.acrossutah.com\/wordpress\/best-of-the-decade\/hoodoos-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=2000%2C1124\" data-orig-size=\"2000,1124\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SD980 IS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1274719529&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Hoodoos\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=500%2C281\" data-large-file=\"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=800%2C450\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"http:\/\/www.acrossutah.com\/wordpress\/best-of-the-decade\/hoodoos-2\/\">Continue reading<\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":1124,"file":"2019\/12\/Hoodoos.jpg","sizes":{"thumbnail":{"file":"Hoodoos-245x245.jpg","width":245,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=245%2C245"},"medium":{"file":"Hoodoos-500x281.jpg","width":500,"height":281,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=500%2C281"},"medium_large":{"file":"Hoodoos-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=768%2C432"},"large":{"file":"Hoodoos-800x450.jpg","width":800,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=800%2C450"},"custom":{"file":"Hoodoos-250x150.jpg","width":250,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=250%2C150"},"post-thumbnail":{"file":"Hoodoos-150x84.jpg","width":150,"height":84,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=150%2C84"},"header":{"file":"Hoodoos-1050x120.jpg","width":1050,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=1050%2C120"},"slider":{"file":"Hoodoos-1050x350.jpg","width":1050,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=1050%2C350"},"parabola-columns":{"file":"Hoodoos-308x201.jpg","width":308,"height":201,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?resize=308%2C201"},"full":{"file":"Hoodoos.jpg?fit=2000%2C1124","width":2000,"height":1124,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg?fit=2000%2C1124"}},"image_meta":{"aperture":"2.8","credit":"","camera":"Canon PowerShot SD980 IS","caption":"","created_timestamp":"1274719529","copyright":"","focal_length":"4.3","iso":"80","shutter_speed":"0.0008","title":"","orientation":"1","keywords":[]}},"post":10011,"source_url":"http:\/\/www.acrossutah.com\/wordpress\/wp-content\/uploads\/2019\/12\/Hoodoos.jpg","_links":{"self":[{"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/media\/10036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.acrossutah.com\/wordpress\/wp-json\/wp\/v2\/comments?post=10036"}]}}